{"id":4836,"date":"2017-11-01T15:24:51","date_gmt":"2017-11-01T14:24:51","guid":{"rendered":"http:\/\/www.iplex.fr\/cadredor\/wordpress\/?page_id=4836"},"modified":"2021-05-17T00:08:09","modified_gmt":"2021-05-16T22:08:09","slug":"atelier","status":"publish","type":"page","link":"http:\/\/www.iplex.fr\/cadredor\/atelier\/","title":{"rendered":"L&#8217;atelier"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; full_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;]<div id=\"ultimate-heading-82046a57adee7aafd\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-82046a57adee7aafd uvc-3574 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-82046a57adee7aafd h1'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h1 style=\"text-decoration:underline;font-style:italic;font-weight:bold;color:#8e685f;margin-top:60px;margin-bottom:50px;\">L'Atelier<\/h1><\/div><div class=\"uvc-sub-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-82046a57adee7aafd .uvc-sub-heading '  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><\/p>\n<h1><img loading=\"lazy\" class=\"aligncenter wp-image-4792 size-thumbnail\" src=\"http:\/\/www.iplex.fr\/cadredor\/wordpress\/wp-content\/uploads\/2016\/08\/32-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"http:\/\/www.iplex.fr\/cadredor\/wp-content\/uploads\/2016\/08\/32-1-150x150.jpg 150w, http:\/\/www.iplex.fr\/cadredor\/wp-content\/uploads\/2016\/08\/32-1-270x270.jpg 270w, http:\/\/www.iplex.fr\/cadredor\/wp-content\/uploads\/2016\/08\/32-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/h1>\n<p><\/div><\/div>[vc_column_text css_animation=&#8221;none&#8221;]Le CADRE D&#8217;OR fut fond\u00e9 en 1978 par Jacques-Henry Varichon : architecte de formation, designer, brillant esprit scientifique tant passionn\u00e9 de g\u00e9om\u00e9trie que de physique et de chimie, il consacra sa vie \u00e0 imaginer et \u00e0 mettre au point des solutions innovantes pour la mise en valeur et la conservation des objets d&#8217;art. Consacr\u00e9<strong><span style=\"color: #ffcc00;\"> &#8220;Artisan d&#8217;excellence&#8221;<\/span> <\/strong>et <strong><span style=\"color: #ffcc00;\">&#8220;Patrimoine vivant&#8221;<\/span><\/strong> il transmit \u00e0 son fils Tymour Varichon tant sa philosophie que son savoir-faire. Le CADRE D&#8217;OR, sous les rennes de ce dernier depuis 2011, b\u00e9n\u00e9ficie de 40 ans d&#8217;exp\u00e9rience pour encadrer, socler et mettre en espace des objets d&#8217;art venus de tous les horizons.<\/p>\n<p>&nbsp;<\/p>\n<p>Tant aupr\u00e8s des mus\u00e9es, galeries, collectionneurs ou particuliers, le CADRE D&#8217;OR se d\u00e9marque par sa ligne sobre et contemporaine dans une constante recherche d&#8217;\u00e9puration et de perfection, avec le plus grand respect des \u0153uvres pr\u00e9sent\u00e9es. Fruit de cette recherche le CADRE D&#8217;OR propose plusieurs proc\u00e9d\u00e9s exclusifs : &#8230; (diplex etc.)[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;5073,5074&#8243; img_size=&#8221;large&#8221; onclick=&#8221;img_link_large&#8221; css=&#8221;.vc_custom_1620844068030{margin-top: 135px !important;background-color: #ffffff !important;}&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; full_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;none&#8221;]Le CADRE D&#8217;OR fut fond\u00e9 en 1978 par Jacques-Henry Varichon : architecte de formation, designer, brillant esprit scientifique tant passionn\u00e9 de g\u00e9om\u00e9trie que de physique et de chimie, il consacra sa vie \u00e0 imaginer et \u00e0 mettre au point des solutions innovantes pour la mise en valeur et la conservation des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/www.iplex.fr\/cadredor\/wp-json\/wp\/v2\/pages\/4836"}],"collection":[{"href":"http:\/\/www.iplex.fr\/cadredor\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.iplex.fr\/cadredor\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.iplex.fr\/cadredor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.iplex.fr\/cadredor\/wp-json\/wp\/v2\/comments?post=4836"}],"version-history":[{"count":6,"href":"http:\/\/www.iplex.fr\/cadredor\/wp-json\/wp\/v2\/pages\/4836\/revisions"}],"predecessor-version":[{"id":6053,"href":"http:\/\/www.iplex.fr\/cadredor\/wp-json\/wp\/v2\/pages\/4836\/revisions\/6053"}],"wp:attachment":[{"href":"http:\/\/www.iplex.fr\/cadredor\/wp-json\/wp\/v2\/media?parent=4836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}